{"id":751,"date":"2021-05-17T18:38:34","date_gmt":"2021-05-17T18:38:34","guid":{"rendered":"https:\/\/labs.100x100.net\/projects\/girbaulab\/?p=751"},"modified":"2022-09-24T18:52:04","modified_gmt":"2022-09-24T18:52:04","slug":"magi-galindo-en-el-innovators-club-de-girbau-lab","status":"publish","type":"post","link":"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/","title":{"rendered":"Mag\u00ed Galindo en el Innovators Club de Girbau LAB"},"content":{"rendered":"<p>Mag\u00ed Galindo, director t\u00e9cnico y cient\u00edfico del Centro internacional de fabricaci\u00f3n avanzada e impresi\u00f3n,\u00a0 \u00a0<a href=\"http:\/\/www.iam3dhub.org\" target=\"_blank\" rel=\"noopener\">IAM3DHub<\/a>, explica los retos y el impacto de la fabricaci\u00f3n aditiva e impresi\u00f3n 3D en una nueva sesi\u00f3n del Innovators Club de Girbau LAB celebrada el pasado 11 de mayo.<\/p>\n<p>El IAM 3D HUB, ubicado dentro del centro tecnol\u00f3gico Leitat, se inaugur\u00f3 el 2018 con el objetivo de acelerar la adopci\u00f3n de tecnolog\u00edas de fabricaci\u00f3n aditiva e impresi\u00f3n 3D en la industria europea como una forma alternativa de dise\u00f1ar, desarrollar y fabricar nuevos productos y servicios competitivos.<br \/>\nSe define como un centro de innovaci\u00f3n digital especializado en fabricaci\u00f3n aditiva e impresi\u00f3n 3D que proporcionar\u00e1 a las pymes una tienda \u00fanica para evaluar, orientar y dirigir todas sus necesidades en fabricaci\u00f3n aditiva.<\/p>\n<p>Con varios ejemplos pr\u00e1cticos, Mag\u00ed explica el rol de la fabricaci\u00f3n aditiva en la industria productiva y su impacto en la producci\u00f3n.<\/p>\n<p>Mag\u00ed destaca que: \u201cla evoluci\u00f3n de la fabricaci\u00f3n aditiva ha transformado la manera de dise\u00f1ar, desarrollar, producir y distribuir productos. Para la industria, a\u00f1ade, estos adelantos han abierto puertas para nuevos dise\u00f1os, productos m\u00e1s \u201climpios\u201d, ligeros y seguros; plazos de entrega m\u00e1s cortos, y costes m\u00e1s bajos, nuevas cadenas de valor y nuevos modelos de negocios\u201d.<\/p>\n<p>Mag\u00ed Galindo concluye la sesi\u00f3n poniendo en valor el rol de la fabricaci\u00f3n aditiva: \u201ca pesar de los retos, el hecho es que la fabricaci\u00f3n aditiva es un conjunto vers\u00e1til de tecnolog\u00edas que pueden apoyar a las empresas de la industria en su investigaci\u00f3n de los imperativos estrat\u00e9gicos de rendimiento, crecimiento e innovaci\u00f3n\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-752 aligncenter\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/09\/Magi_Galindo.jpg\" alt=\"Mag\u00ed Galindo at the Innovators Club of Girbau LAB\" width=\"479\" height=\"639\" srcset=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/09\/Magi_Galindo.jpg 479w, https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/09\/Magi_Galindo-225x300.jpg 225w\" sizes=\"auto, (max-width: 479px) 100vw, 479px\" \/><\/p>\n<h3>1. &#8211; C\u00f3mo se vincula la innovaci\u00f3n con las tecnolog\u00edas de fabricaci\u00f3n aditiva y la impresi\u00f3n 3D?<\/h3>\n<p>Entendiendo que innovar es introducir algo nuevo (en una cosa) y que tenga \u00e9xito, la fabricaci\u00f3n aditiva se vincula a la innovaci\u00f3n en dos \u00e1mbitos. Es fuente de innovaci\u00f3n en producto y es causa de la transformaci\u00f3n de la cadena de suministro.<\/p>\n<p>En cuanto al producto: aporta una gran reducci\u00f3n de las constricciones de dise\u00f1o -complejidad, ligereza, consolidaci\u00f3n de conjuntos en componente \u00fanico, etc.-; la capacidad de incorporar personalizaci\u00f3n, dise\u00f1ar (multi) funcionalidades, o funcionalidades mejoradas; abre camino a nuevas est\u00e9ticas y al dise\u00f1o de productos m\u00e1s sostenibles por el hecho de producirse aditivamente. En resumen, como tecnolog\u00eda digital, aporta una manera nueva de dise\u00f1ar y producir: productos m\u00e1s seguros, m\u00e1s ligeros, m\u00e1s eficientes, m\u00e1s r\u00e1pidos, menos costosos y m\u00e1s personalizados.<\/p>\n<p>En cuanto a la cadena de suministro: elimina la necesidad de herramientas productivas, acorta la cadena y, por lo tanto, el tiempo de introducci\u00f3n de los productos en el mercado. Del dise\u00f1o se pasa directamente a la producci\u00f3n, haciendo desaparecer la fase de industrializaci\u00f3n y acortando el proceso productivo.<br \/>\nHace viable la producci\u00f3n de componentes \u00fanicos y peque\u00f1as series, permitiendo incrementar la variedad de productos y las familias de un producto determinado. La consecuencia es que permite servir mejor a nichos y mercados de consumo y todo esto sin la necesidad de un amplio despliegue de capital.<\/p>\n<p>Se produce bajo pedido, lo que supone una reducci\u00f3n de los costes de inventario; y en el lugar de consumo, es decir la producci\u00f3n se descentralizada y esto reduce los costes log\u00edsticos.<\/p>\n<h3>2.-C\u00f3mo est\u00e1 cambiando la fabricaci\u00f3n aditiva los m\u00e9todos de producci\u00f3n de las empresas?<\/h3>\n<p>La fabricaci\u00f3n aditiva puede impactar toda la cadena de valor de las empresas, no \u00fanicamente la parte operativa de la producci\u00f3n.<\/p>\n<p>Actualmente, estas tecnolog\u00edas ya son una herramienta corriente y habitual en toda empresa que dise\u00f1a y desarrolla productos, del mismo modo que lo son las herramientas CAD y CAE.<\/p>\n<p>Pero los cambios pueden ir m\u00e1s all\u00e1.<\/p>\n<p>Aunque la empresa no cambie los m\u00e9todos de producci\u00f3n, la fabricaci\u00f3n aditiva ya aporta soluciones de mejora y eficiencia a sus procesos productivos. Durante la fase de industrializaci\u00f3n facilita la obtenci\u00f3n de utillajes de ayuda a la producci\u00f3n (utillaje de manipulaci\u00f3n, fijaci\u00f3n, posicionamiento, verificaci\u00f3n, transporte en l\u00ednea, montaje, programaci\u00f3n\u2026) y, incluso, la obtenci\u00f3n de herramientas de fabricaci\u00f3n (moldes de fundici\u00f3n, fundici\u00f3n inyectada, inyecci\u00f3n, conformaci\u00f3n, estampado\u2026)<\/p>\n<p>Cuando la innovaci\u00f3n en producto ha introducido nuevos dise\u00f1os, pensados para ser producidos con tecnolog\u00edas aditivas, la transformaci\u00f3n de los m\u00e9todos de producci\u00f3n es muy clara y acentuada. Casi podr\u00edamos decir que es radical. La fase de industrializaci\u00f3n pr\u00e1cticamente no existe, las herramientas de producci\u00f3n no existen y los procesos productivos aditivos requieren de operaciones bastante diferentes si las comparamos con las operaciones de los m\u00e9todos de producci\u00f3n con tecnolog\u00edas m\u00e1s convencionales. Lo que no cambia tanto, aunque existen diferencias, es, quiz\u00e1s, el uso de tecnolog\u00edas para el post-proceso y tratamiento, y los m\u00e9todos de control de calidad y verificaci\u00f3n.<\/p>\n<p>Por otro lado, la producci\u00f3n ligada al mantenimiento del producto en el mercado (piezas de repuesto) tambi\u00e9n est\u00e1 encontrando en la fabricaci\u00f3n aditiva una alternativa innovadora.<\/p>\n<h3>3.-C\u00f3mo se aplica la innovaci\u00f3n en IAM 3D HUB?<\/h3>\n<p>El IAM3DHub naci\u00f3 con la vocaci\u00f3n de acelerar la adopci\u00f3n de las tecnolog\u00edas de fabricaci\u00f3n aditiva y dotar las empresas de herramientas que habilitaran una nueva forma de dise\u00f1ar y de producir. Por lo tanto, todos los recursos, tanto humanos como tecnol\u00f3gicos, y los servicios del Hub han sido seleccionados, pensados y dise\u00f1ados para acompa\u00f1ar las empresas en su camino de adopci\u00f3n de la fabricaci\u00f3n aditiva como herramienta estrat\u00e9gica de innovaci\u00f3n.<\/p>\n<p>Se ha creado un entorno de experimentaci\u00f3n y ensayo de las tecnolog\u00edas de fabricaci\u00f3n aditiva y se ha puesto a disposici\u00f3n de las empresas. De este modo, sin necesidad de ponerse en ning\u00fan riesgo de inversi\u00f3n, las empresas tienen acceso a un gran n\u00famero de tecnolog\u00edas y equipos de impresi\u00f3n 3D, de \u00faltima generaci\u00f3n.<\/p>\n<p>A la vez, se provee las empresas de servicios de informaci\u00f3n, gu\u00eda, asesoramiento y acompa\u00f1amiento (mentoring) en su particular proceso de adopci\u00f3n e implementaci\u00f3n de estas tecnolog\u00edas en cuanto a selecci\u00f3n, criba de los \u00e1mbitos de aplicaci\u00f3n donde se prev\u00e9 obtener mayor beneficio y rentabilidad, as\u00ed como en la elaboraci\u00f3n de planes de negocio ligados a su adopci\u00f3n.<\/p>\n<p>As\u00ed mismo, se proveen servicios que denominamos proyectos \u201cend-to-end\u201d, es decir, que se inician en el dise\u00f1o, contin\u00faan con la producci\u00f3n y acaban con la caracterizaci\u00f3n, validaci\u00f3n y, si hace falta, la certificaci\u00f3n de nuevos productos o aplicaciones basadas en fabricaci\u00f3n aditiva. El objetivo es que al acabado del proyecto la empresa tenga el conocimiento, la experiencia y la informaci\u00f3n necesaria para tomar decisiones para la adopci\u00f3n de estas tecnolog\u00edas.<\/p>\n<p>Y, por \u00faltimo, y no menos importante que los anteriores, el IAM3D Hub ofrece formaci\u00f3n y entrenamiento en estas tecnolog\u00edas, para dotar las empresas de personal preparado para obtener el mayor rendimiento.<\/p>\n<p>El propio IAM3DHub cada d\u00eda tiene que afrontar nuevos retos planteados por las empresas, del que esperan soluciones innovadoras, y esto quiere decir que tenemos que introducir algo de nuevo en cada cosa que hacemos y hacerlo de nuevas maneras, m\u00e1s eficientes y con m\u00e1s aportaci\u00f3n de valor.<\/p>\n<h3>4.-Cu\u00e1l es la forma \u00f3ptima de potenciar la innovaci\u00f3n conjunta entre una corporaci\u00f3n y una startup?<\/h3>\n<p>No soy experto en estrategias de colaboraci\u00f3n entre Corporaciones y Startups, y por tanto me es extremadamente dif\u00edcil decir cu\u00e1l es la forma \u00f3ptima de potenciar la innovaci\u00f3n conjunta entre ellas.<\/p>\n<p>Me pareci\u00f3 bastante interesante un art\u00edculo del IESE, \u201cGu\u00eda pr\u00e1ctica para la colaboraci\u00f3n entre corporaciones y startups\u201d sobre la publicaci\u00f3n \u201cCorporate Venturing: Achieving Profitable Growth Through Startups\u201d del 2017, dirigida por Julia Prats y Pau Amig\u00f3. En este art\u00edculo se dice que no hay una sola manera de hacer, sino que las opciones son m\u00faltiples, y recojo a modo de lista las f\u00f3rmulas que se presentan: Recursos compartidos, Competici\u00f3n, Hackathon, Scouting, Alianza estrat\u00e9gica, Incubadora, Aceleradora, Excubadora, Capital riesgo y Programa de adquisiciones. El sentido com\u00fan me dice que ninguna de ellas es la mejor ni la \u00f3ptima, que depender\u00e1 de la corporaci\u00f3n y de la startup, del \u00e1mbito tecnol\u00f3gico y del sector industrial del que se trate. El que s\u00ed har\u00e1 falta es conocer qu\u00e9 es y que aporta cada una de estas f\u00f3rmulas y, una vez analizadas, proponer aquella o la combinaci\u00f3n de aquellas que se prev\u00e9 m\u00e1s adecuada para la colaboraci\u00f3n que se quiere establecer.<\/p>\n<h3>5.-Qu\u00e9 mejoras en eficiencia y sostenibilidad visualizas para la industria de la lavander\u00eda en los pr\u00f3ximos 5 a\u00f1os?<\/h3>\n<p>De nuevo no soy la persona m\u00e1s adecuada para dar respuesta a esta pregunta. No obstante, he pedido asesoramiento a una persona muy experta y referente en este \u00e1mbito, la Dra. Rosa Escudero, compa\u00f1era m\u00eda en Leitat, que me ha facilitado sus reflexiones. Miro de hacer un extracto, pero el que aconsejar\u00eda es invitarla a ella a una de las sesiones de innovaci\u00f3n de Girbau.<\/p>\n<p>Hoy, la lavander\u00eda va ligada a tres grandes pilares, los electrodom\u00e9sticos -lavadoras- con el tratamiento de la ropa, los textiles y los detergentes. Las mejoras en cada uno de ellos impacta e impactar\u00e1 inevitablemente en los otros dos.<\/p>\n<p>Si nos referimos a las tendencias innovadoras espec\u00edficamente en las lavadoras y el proceso de lavado de la ropa podemos hablar de la aplicaci\u00f3n generalizada del reglamento de ecodise\u00f1o, la mejora en el suministro y el uso de energ\u00eda y agua, la tecnolog\u00eda de eje horizontal (mejor rendimiento), el piloto autom\u00e1tico de la lavadora: sensores que identifican la carga, los tipos de tejidos, el nivel y los tipos de suciedad, y que realizan escaneos espectrosc\u00f3picos del l\u00edquido de lavado por si se necesitan tratamientos adicionales. La reducci\u00f3n de la acci\u00f3n mec\u00e1nica para evitar la abrasi\u00f3n de los tejidos. M\u00e1quinas de pomo y bot\u00f3n pasan a m\u00e1quinas con pantallas t\u00e1ctiles (con innumerables programas). Los usuarios personalizan su experiencia de lavado combinando diferentes condiciones, lo que da lugar a sus ciclos favoritos. Al detectar el tipo de piezas, por lectura de identificadores (etiquetas RFID?), se autoprograma el mejor ciclo de lavado. Frente los olores, por crecimiento de biofilm, se responde con sensores de biofilm y programas de auto limpieza. Para la combinaci\u00f3n gente mayor + escasez de recursos energ\u00e9ticos y de agua, se responde con medidas de prevenci\u00f3n de infecciones y requisitos higi\u00e9nicos.<\/p>\n<p>Si observamos las tendencias de innovaci\u00f3n en los textiles tendremos que hablar de tejidos con funcionalidades mejoradas, protecci\u00f3n frente a contaminantes, microorganismos, fatiga personal, sudor\u2026 nuevas estructuras de fibras, nuevos materiales (fibras naturales bio-basadas), materiales compuestos, recubrimientos funcionalizantes a niveles micro y nano, integraci\u00f3n de electr\u00f3nica en la ropa, propiedades inteligentes con capacidad de actuar seg\u00fan un est\u00edmulo externo, desarrollos en impresi\u00f3n 3D, etc.<\/p>\n<p>Y, finalmente, en el campo de los detergentes, tambi\u00e9n destaca un conjunto de tendencias de innovaci\u00f3n.<\/p>\n<p>En cuanto a sus ingredientes, se desarrollan materias primas de alto rendimiento, totalmente renovables y biodegradables, de origen natural con un perfil menos agresivo y con ingredientes para nuevas aplicaciones, multifuncionales.<\/p>\n<p>Se proponen detergentes polivalentes con acci\u00f3n suavizante y de quitamanchas donde la fragancia es clave. Detergentes con propiedades neutralizadoras de los olores, fragancias de larga duraci\u00f3n, refuerzos de olores al lavado y emulaci\u00f3n de los mercados de los perfumes de belleza (Aceite de arg\u00e1n), con evocaci\u00f3n de lugares ex\u00f3ticos (amazonas, caribe) olores que mejoran el sue\u00f1o (espliego)\u2026 La eliminaci\u00f3n de las manchas es el segmento m\u00e1s activo en innovaci\u00f3n: Oxy products, Dispositivos\/c\u00e1psulas para la combinaci\u00f3n de polos\/l\u00edquidos\/hielos, productos para manchas espec\u00edficas\u2026<\/p>\n<p>Se desarrollan detergentes para tratamientos preventivos de los tejidos y para restaurar las propiedades como, por ejemplo, de resistencia a las manchas o de hidrofobia.<\/p>\n<p>Cada d\u00eda es m\u00e1s importante la preocupaci\u00f3n por el impacto ambiental de estos productos y se busca que sean cada d\u00eda m\u00e1s ecol\u00f3gicos y sostenibles, es decir, para lavar en temperaturas m\u00e1s bajas, de m\u00e1s f\u00e1cil enjuagado, alejados de los productos qu\u00edmicos y basados en ingredientes bot\u00e1nicos, \u00e1cido c\u00edtrico, etc. Para cuidar la salud, las pieles sensibles, los detergentes se testan dermatol\u00f3gicamente.<\/p>\n<p>Estas mejoras e innovaciones son mayoritariamente debidas a la aplicaci\u00f3n de las que se denominan KETs, -key enable technologies-, entre ellas la nanotecnolog\u00eda, la biotecnolog\u00eda, la fot\u00f3nica, el internet de las cosas, la autom\u00e1tica y la rob\u00f3tica, etc. cuando se aplican a los detergentes, a los nuevos textiles y a los electrodom\u00e9sticos.<\/p>\n<p>La combinaci\u00f3n de mejoras aportadas por estas tecnolog\u00edas, en los tres pilares, puede dar lugar a innovaciones disruptivas.<\/p>\n<h3>6.-C\u00f3mo se lavar\u00e1 la ropa en el 2050?<\/h3>\n<p>Hace quince a\u00f1os, trabajando en la Fundaci\u00f3n Eduard Soler, en Ripoll, hice un video, donde explicaba c\u00f3mo la fabricaci\u00f3n aditiva hab\u00eda resuelto mediante la impresi\u00f3n de moldes de arena, en poco tiempo y con poco esfuerzo econ\u00f3mico, la obtenci\u00f3n de 30 bloques de motores el\u00e9ctricos -seis modelos de motor y cinco copias de cada. Y acababa el video con la frase de Alan Key: \u201cThe best way to predict the future is ton invent it\u201d, a la que a\u00f1ad\u00ed, \u201cy la mejor manera de darle forma es empezar a dise\u00f1arlo y construirlo\u201d. La aplicaci\u00f3n de la impresi\u00f3n 3D de moldes de arena era bastante innovadora en aquel momento, ahora es muy frecuente usarlo, y de aqu\u00ed a diez a\u00f1os ser\u00e1 un proceso totalmente extendido y establecido.<\/p>\n<p>C\u00f3mo se lavar\u00e1 la ropa de aqu\u00ed a 30 a\u00f1os, no lo s\u00e9, pero s\u00ed que estoy totalmente seguro de que depender\u00e1, en gran parte, de la investigaci\u00f3n y de los desarrollos que seamos capaces de llevar a cabo hoy.<\/p>\n<p>Las tecnolog\u00edas digitales, cada d\u00eda m\u00e1s presentes en nuestros productos, concretamente la fot\u00f3nica, la electr\u00f3nica, la conectividad de los productos, la inteligencia artificial y la rob\u00f3tica ser\u00e1n los vectores que conducir\u00e1n los cambios en el c\u00f3mo trataremos la \u201cropa\u201d de aqu\u00ed a treinta a\u00f1os.<\/p>\n<p>Y como he dicho antes, no depender\u00e1 solo de los adelantos en el electrodom\u00e9stico, sino tambi\u00e9n de la evoluci\u00f3n de los textiles y de los productos de limpieza. Cada d\u00eda ser\u00e1 m\u00e1s necesario reunir los tres pilares en un mismo entorno de innovaci\u00f3n ya que cada uno de ellos avanzar\u00e1 con los adelantos de los otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mag\u00ed Galindo, director t\u00e9cnico y cient\u00edfico del Centro internacional de fabricaci\u00f3n avanzada e impresi\u00f3n,\u00a0 \u00a0IAM3DHub, explica los retos y el impacto de la fabricaci\u00f3n aditiva e impresi\u00f3n 3D en una nueva sesi\u00f3n del Innovators Club de Girbau LAB celebrada el pasado 11 de mayo. El IAM 3D HUB, ubicado dentro del centro tecnol\u00f3gico Leitat, se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":755,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15],"class_list":["post-751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-club-de-innovadores"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mag\u00ed Galindo en el Innovators Club de Girbau LAB - Girbau LAB<\/title>\n<meta name=\"description\" content=\"Mag\u00ed Galindo, director t\u00e9cnico y cient\u00edfico de IAM3DHub, explica los retos de la fabricaci\u00f3n aditiva e impresi\u00f3n 3D en el Club de Girbau LAB\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mag\u00ed Galindo en el Innovators Club de Girbau LAB - Girbau LAB\" \/>\n<meta property=\"og:description\" content=\"Mag\u00ed Galindo, director t\u00e9cnico y cient\u00edfico de IAM3DHub, explica los retos de la fabricaci\u00f3n aditiva e impresi\u00f3n 3D en el Club de Girbau LAB\" \/>\n<meta property=\"og:url\" content=\"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/\" \/>\n<meta property=\"og:site_name\" content=\"Girbau LAB\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-17T18:38:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-24T18:52:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/09\/iam3dhub.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1289\" \/>\n\t<meta property=\"og:image:height\" content=\"840\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"girbau\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@girbaulab\" \/>\n<meta name=\"twitter:site\" content=\"@girbaulab\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"girbau\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/\"},\"author\":{\"name\":\"girbau\",\"@id\":\"https:\/\/www.girbaulab.com\/es\/#\/schema\/person\/23b9b3863288ce7c33d38f38f3a3af5f\"},\"headline\":\"Mag\u00ed Galindo en el Innovators Club de Girbau LAB\",\"datePublished\":\"2021-05-17T18:38:34+00:00\",\"dateModified\":\"2022-09-24T18:52:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/\"},\"wordCount\":2572,\"publisher\":{\"@id\":\"https:\/\/www.girbaulab.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/09\/iam3dhub.jpg\",\"articleSection\":[\"Club de Innovadores\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/\",\"url\":\"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/\",\"name\":\"Mag\u00ed Galindo en el Innovators Club de Girbau LAB - Girbau LAB\",\"isPartOf\":{\"@id\":\"https:\/\/www.girbaulab.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/09\/iam3dhub.jpg\",\"datePublished\":\"2021-05-17T18:38:34+00:00\",\"dateModified\":\"2022-09-24T18:52:04+00:00\",\"description\":\"Mag\u00ed Galindo, director t\u00e9cnico y cient\u00edfico de IAM3DHub, explica los retos de la fabricaci\u00f3n aditiva e impresi\u00f3n 3D en el Club de Girbau LAB\",\"breadcrumb\":{\"@id\":\"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/#primaryimage\",\"url\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/09\/iam3dhub.jpg\",\"contentUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/09\/iam3dhub.jpg\",\"width\":1289,\"height\":840,\"caption\":\"Mag\u00ed Galindo at the Innovators Club of Girbau LAB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.girbaulab.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mag\u00ed Galindo en el Innovators Club de Girbau LAB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.girbaulab.com\/es\/#website\",\"url\":\"https:\/\/www.girbaulab.com\/es\/\",\"name\":\"Girbau LAB\",\"description\":\"Girbau LAB is a space for collaboration created to add value to the laundry industry through innovation\",\"publisher\":{\"@id\":\"https:\/\/www.girbaulab.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.girbaulab.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.girbaulab.com\/es\/#organization\",\"name\":\"Girbau LAB\",\"url\":\"https:\/\/www.girbaulab.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.girbaulab.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/10\/Girbau_LAB_logo.png\",\"contentUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/10\/Girbau_LAB_logo.png\",\"width\":562,\"height\":90,\"caption\":\"Girbau LAB\"},\"image\":{\"@id\":\"https:\/\/www.girbaulab.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/girbaulab\",\"https:\/\/www.linkedin.com\/company\/girbaulab\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.girbaulab.com\/es\/#\/schema\/person\/23b9b3863288ce7c33d38f38f3a3af5f\",\"name\":\"girbau\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.girbaulab.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fe57a3f139ea81c65a338e37a8064b4e80844f839737532820c9107eb9e1966f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fe57a3f139ea81c65a338e37a8064b4e80844f839737532820c9107eb9e1966f?s=96&d=mm&r=g\",\"caption\":\"girbau\"},\"sameAs\":[\"https:\/\/labs.100x100.net\/projects\/girbaulab\/private\"],\"url\":\"https:\/\/girbaulab.com\/es\/author\/girbau\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mag\u00ed Galindo en el Innovators Club de Girbau LAB - Girbau LAB","description":"Mag\u00ed Galindo, director t\u00e9cnico y cient\u00edfico de IAM3DHub, explica los retos de la fabricaci\u00f3n aditiva e impresi\u00f3n 3D en el Club de Girbau LAB","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/","og_locale":"es_ES","og_type":"article","og_title":"Mag\u00ed Galindo en el Innovators Club de Girbau LAB - Girbau LAB","og_description":"Mag\u00ed Galindo, director t\u00e9cnico y cient\u00edfico de IAM3DHub, explica los retos de la fabricaci\u00f3n aditiva e impresi\u00f3n 3D en el Club de Girbau LAB","og_url":"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/","og_site_name":"Girbau LAB","article_published_time":"2021-05-17T18:38:34+00:00","article_modified_time":"2022-09-24T18:52:04+00:00","og_image":[{"width":1289,"height":840,"url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/09\/iam3dhub.jpg","type":"image\/jpeg"}],"author":"girbau","twitter_card":"summary_large_image","twitter_creator":"@girbaulab","twitter_site":"@girbaulab","twitter_misc":{"Escrito por":"girbau","Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/#article","isPartOf":{"@id":"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/"},"author":{"name":"girbau","@id":"https:\/\/www.girbaulab.com\/es\/#\/schema\/person\/23b9b3863288ce7c33d38f38f3a3af5f"},"headline":"Mag\u00ed Galindo en el Innovators Club de Girbau LAB","datePublished":"2021-05-17T18:38:34+00:00","dateModified":"2022-09-24T18:52:04+00:00","mainEntityOfPage":{"@id":"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/"},"wordCount":2572,"publisher":{"@id":"https:\/\/www.girbaulab.com\/es\/#organization"},"image":{"@id":"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/#primaryimage"},"thumbnailUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/09\/iam3dhub.jpg","articleSection":["Club de Innovadores"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/","url":"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/","name":"Mag\u00ed Galindo en el Innovators Club de Girbau LAB - Girbau LAB","isPartOf":{"@id":"https:\/\/www.girbaulab.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/#primaryimage"},"image":{"@id":"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/#primaryimage"},"thumbnailUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/09\/iam3dhub.jpg","datePublished":"2021-05-17T18:38:34+00:00","dateModified":"2022-09-24T18:52:04+00:00","description":"Mag\u00ed Galindo, director t\u00e9cnico y cient\u00edfico de IAM3DHub, explica los retos de la fabricaci\u00f3n aditiva e impresi\u00f3n 3D en el Club de Girbau LAB","breadcrumb":{"@id":"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/#primaryimage","url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/09\/iam3dhub.jpg","contentUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/09\/iam3dhub.jpg","width":1289,"height":840,"caption":"Mag\u00ed Galindo at the Innovators Club of Girbau LAB"},{"@type":"BreadcrumbList","@id":"https:\/\/girbaulab.com\/es\/magi-galindo-en-el-innovators-club-de-girbau-lab\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.girbaulab.com\/es\/"},{"@type":"ListItem","position":2,"name":"Mag\u00ed Galindo en el Innovators Club de Girbau LAB"}]},{"@type":"WebSite","@id":"https:\/\/www.girbaulab.com\/es\/#website","url":"https:\/\/www.girbaulab.com\/es\/","name":"Girbau LAB","description":"Girbau LAB is a space for collaboration created to add value to the laundry industry through innovation","publisher":{"@id":"https:\/\/www.girbaulab.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.girbaulab.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.girbaulab.com\/es\/#organization","name":"Girbau LAB","url":"https:\/\/www.girbaulab.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.girbaulab.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/10\/Girbau_LAB_logo.png","contentUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/10\/Girbau_LAB_logo.png","width":562,"height":90,"caption":"Girbau LAB"},"image":{"@id":"https:\/\/www.girbaulab.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/girbaulab","https:\/\/www.linkedin.com\/company\/girbaulab\/"]},{"@type":"Person","@id":"https:\/\/www.girbaulab.com\/es\/#\/schema\/person\/23b9b3863288ce7c33d38f38f3a3af5f","name":"girbau","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.girbaulab.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fe57a3f139ea81c65a338e37a8064b4e80844f839737532820c9107eb9e1966f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe57a3f139ea81c65a338e37a8064b4e80844f839737532820c9107eb9e1966f?s=96&d=mm&r=g","caption":"girbau"},"sameAs":["https:\/\/labs.100x100.net\/projects\/girbaulab\/private"],"url":"https:\/\/girbaulab.com\/es\/author\/girbau\/"}]}},"_links":{"self":[{"href":"https:\/\/girbaulab.com\/es\/wp-json\/wp\/v2\/posts\/751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/girbaulab.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/girbaulab.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/girbaulab.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/girbaulab.com\/es\/wp-json\/wp\/v2\/comments?post=751"}],"version-history":[{"count":3,"href":"https:\/\/girbaulab.com\/es\/wp-json\/wp\/v2\/posts\/751\/revisions"}],"predecessor-version":[{"id":766,"href":"https:\/\/girbaulab.com\/es\/wp-json\/wp\/v2\/posts\/751\/revisions\/766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/girbaulab.com\/es\/wp-json\/wp\/v2\/media\/755"}],"wp:attachment":[{"href":"https:\/\/girbaulab.com\/es\/wp-json\/wp\/v2\/media?parent=751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/girbaulab.com\/es\/wp-json\/wp\/v2\/categories?post=751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}