{"id":4108,"date":"2026-03-10T23:42:57","date_gmt":"2026-03-10T23:42:57","guid":{"rendered":"https:\/\/girbaulab.com\/pere-llorach-massana-housing-cooperatives-towards-a-fairer-and-more-sustainable-model\/"},"modified":"2026-03-11T00:04:09","modified_gmt":"2026-03-11T00:04:09","slug":"pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible","status":"publish","type":"post","link":"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/","title":{"rendered":"Pere Llorach Massana. Las cooperativas de vivienda: hacia un modelo m\u00e1s justo y sostenible"},"content":{"rendered":"<p>En esta primera sesi\u00f3n del Club de Innovadores 2026 exploramos el modelo de las cooperativas de vivienda con Pere Llorach, investigador, docente e ingeniero especializado en la intersecci\u00f3n entre el dise\u00f1o industrial, la sostenibilidad ambiental y la econom\u00eda circular.<\/p>\n<p><strong>\u00bfPor qu\u00e9 el modelo de cooperativa de vivienda?<br \/>\n<\/strong><\/p>\n<p>Las cooperativas de vivienda son un modelo sin \u00e1nimo de lucro que permite a un conjunto de personas con un objetivo com\u00fan -acceder a una vivienda- hacerlo a trav\u00e9s de la autopromoci\u00f3n. Este sistema evita intermediarios y hace que el coste final de la vivienda sea el precio de coste, sin terceras personas que especulen con el proyecto.<\/p>\n<p>Adem\u00e1s, dentro del marco legal en el que operan, las cooperativas funcionan de manera democr\u00e1tica y participativa. Las personas que forman parte de ellas toman las decisiones de forma colectiva y pueden participar en aspectos como el tama\u00f1o de las viviendas, los costes, los materiales o la elecci\u00f3n del equipo arquitect\u00f3nico.<\/p>\n<p>Esto permite acceder a una vivienda con una capacidad de decisi\u00f3n mucho mayor sobre el proyecto.<\/p>\n<p>Las cooperativas tambi\u00e9n pueden convertirse en una base sobre la cual incorporar otras dimensiones al proyecto residencial. Por ejemplo, permiten impulsar viviendas m\u00e1s sostenibles o crear espacios que fomenten la dinamizaci\u00f3n vecinal y la cohesi\u00f3n entre las personas que comparten un mismo edificio.<\/p>\n<p>En este sentido, el modelo cooperativo puede entenderse como una estructura flexible a partir de la cual se pueden incorporar distintas capas de impacto social o ambiental.<\/p>\n<p><strong>\u00bfQu\u00e9 impactos sociales y ambientales puede generar una cooperativa de vivienda?<br \/>\n<\/strong><\/p>\n<p>Desde un punto de vista social, las cooperativas de vivienda contribuyen a cuestionar el individualismo que a menudo caracteriza a las sociedades actuales. El hecho de tomar decisiones de forma colaborativa implica confiar en otras personas y construir proyectos compartidos.<\/p>\n<p>Este proceso puede ayudar a superar una visi\u00f3n basada en la desconfianza o el miedo a la convivencia. De hecho, gran parte del mundo que hemos construido -edificios, tecnolog\u00edas o conocimiento- es fruto de la colaboraci\u00f3n.<\/p>\n<p>Las cooperativas de vivienda recuperan esta l\u00f3gica colaborativa en el \u00e1mbito de la vivienda y favorecen formas de convivencia m\u00e1s conectadas. Permiten reconocer que las personas que viven cerca tambi\u00e9n tienen necesidades y que es posible generar relaciones de apoyo mutuo.<\/p>\n<p>Adem\u00e1s, muchas cooperativas incorporan espacios comunitarios para las personas residentes y, en algunos casos, estos espacios tambi\u00e9n se abren al barrio o al pueblo. Esto facilita la dinamizaci\u00f3n social y crea v\u00ednculos entre el proyecto y su entorno.<\/p>\n<p>Desde el punto de vista ambiental, el modelo cooperativo tambi\u00e9n ofrece oportunidades interesantes. Como el proyecto se construye de forma colectiva, es posible incorporar criterios de sostenibilidad en el dise\u00f1o de las viviendas: edificios bien aislados, sistemas energ\u00e9ticos eficientes o el uso de materiales m\u00e1s naturales.<\/p>\n<p>De este modo, las cooperativas de vivienda pueden convertirse en referentes de nuevas formas de construir y habitar.<\/p>\n<p><strong>Hablemos de vuestro proyecto, La Tremolina. \u00bfC\u00f3mo surgi\u00f3?<\/strong><\/p>\n<p>La Tremolina es un proyecto de cooperativa de vivienda rural con caracter\u00edsticas bastante singulares. Se trata de un proyecto peque\u00f1o, con cinco unidades de convivencia, que tambi\u00e9n cuenta con un patio central con una zona de huerto y un terreno destinado a otras actividades.<\/p>\n<p>El proyecto surgi\u00f3 a partir de un grupo de personas neorrurales que se hab\u00edan instalado en el Pallars y buscaban una forma diferente de vivir. La idea era combinar espacios privados \u2014peque\u00f1as viviendas con cocina, comedor, ba\u00f1o y habitaci\u00f3n\u2014 con espacios comunitarios donde compartir momentos y actividades.<\/p>\n<p>El proyecto respond\u00eda a la voluntad de vivir en comunidad sin renunciar a un espacio privado propio. Al mismo tiempo, se buscaba que las personas que compartieran el edificio no fueran desconocidas, sino una comunidad basada en la confianza, el apoyo mutuo y el cuidado.<\/p>\n<p>Esta convivencia permite compartir momentos cotidianos, apoyarse en distintas etapas de la vida \u2014como la crianza\u2014 o simplemente generar una red de relaciones m\u00e1s cercana.<\/p>\n<p>El proyecto tambi\u00e9n incorpora una dimensi\u00f3n territorial. Las personas impulsoras se planteaban qu\u00e9 pod\u00edan aportar al territorio que las acog\u00eda. Por ello, desde el principio se pens\u00f3 que algunos espacios del proyecto pudieran abrirse al pueblo, ya fuera para acoger actividades o para generar espacios de encuentro con la comunidad local.<\/p>\n<p>Con el tiempo, todas estas ideas fueron tomando forma hasta configurar el espacio que hoy es La Tremolina.<\/p>\n<p><strong>\u00bfQu\u00e9 aprendizajes y retos aporta este caso?<\/strong><\/p>\n<p>Uno de los principales aprendizajes de proyectos como La Tremolina es mostrar que no existe una \u00fanica forma de habitar.<\/p>\n<p>Las formas de vivienda que conocemos suelen responder a h\u00e1bitos o convenciones sociales que rara vez cuestionamos. Experiencias como esta permiten abrir imaginarios y demostrar que es posible construir otros modelos de convivencia.<\/p>\n<p>Vivir en comunidad, sin embargo, tambi\u00e9n implica retos. Requiere energ\u00eda, capacidad de di\u00e1logo y voluntad de alcanzar acuerdos con otras personas.<\/p>\n<p>Esto conlleva un aprendizaje importante en t\u00e9rminos de gesti\u00f3n emocional y resoluci\u00f3n de conflictos. No siempre habr\u00e1 consenso y ser\u00e1 necesario hablar, escuchar y buscar soluciones compartidas.<\/p>\n<p>En realidad, estos procesos forman parte de muchas otras esferas de la vida cotidiana: las relaciones laborales, las amistades o las relaciones de pareja. Los proyectos comunitarios simplemente hacen m\u00e1s visible la necesidad de construir herramientas colectivas para gestionar la convivencia.<\/p>\n<p>Para muchas personas, este esfuerzo tambi\u00e9n se traduce en beneficios significativos: una red de apoyo m\u00e1s amplia, m\u00e1s compa\u00f1\u00eda y un sentimiento de comunidad m\u00e1s fuerte.<\/p>\n<p>En este sentido, proyectos como La Tremolina tambi\u00e9n representan un ejercicio de superar miedos y atreverse a imaginar formas de vida diferentes.<\/p>\n<p><strong>\u00bfEspacios como una lavander\u00eda compartida pueden cambiar la manera en que nos relacionamos?<\/strong><\/p>\n<p>Los espacios comunitarios desempe\u00f1an un papel importante en la construcci\u00f3n de relaciones.<\/p>\n<p>En La Tremolina hay diversos elementos compartidos, como una lavadora y un horno utilizados por nueve personas. Este sistema tiene ventajas claras desde el punto de vista de los recursos: se necesitan menos electrodom\u00e9sticos, se consume menos energ\u00eda y se ocupa menos espacio.<\/p>\n<p>Pero tambi\u00e9n tiene un impacto social. El uso de estos espacios genera encuentros cotidianos entre las personas que viven en el proyecto.<\/p>\n<p>Estas interacciones, aunque sean breves, contribuyen a reforzar los v\u00ednculos y a hacer m\u00e1s visibles a las otras personas de la comunidad.<\/p>\n<p>Cuando todos los servicios se encuentran dentro del espacio privado de la vivienda, es m\u00e1s f\u00e1cil que la vida cotidiana se desarrolle de forma aislada. En cambio, los espacios compartidos generan oportunidades de encuentro y ayudan a romper ese aislamiento.<\/p>\n<p>Incluso interacciones muy simples pueden tener un papel relevante en la dinamizaci\u00f3n social de la comunidad.<\/p>\n<p><strong>\u00bfC\u00f3mo crees que lavaremos la ropa en 2040?<\/strong><\/p>\n<p>Es dif\u00edcil dar una respuesta \u00fanica. Probablemente convivir\u00e1n diferentes modelos.<\/p>\n<p>Habr\u00e1 personas que seguir\u00e1n utilizando lavander\u00edas con m\u00e1quinas industriales, otras que tendr\u00e1n su propia lavadora en casa y tambi\u00e9n comunidades que optar\u00e1n por sistemas compartidos.<\/p>\n<p>Desde una perspectiva de eficiencia, los sistemas comunitarios tienen mucho sentido, aunque no es seguro que todo el mundo est\u00e9 dispuesto a adoptarlos.<\/p>\n<p>Lo que s\u00ed parece previsible es que la tecnolog\u00eda de las lavadoras contin\u00fae evolucionando para reducir el consumo de agua, energ\u00eda y detergentes.<\/p>\n<p>Tambi\u00e9n es probable que el debate sobre los micropl\u00e1sticos gane importancia. Esto puede implicar mejoras en los filtros de las lavadoras, pero tambi\u00e9n una reflexi\u00f3n m\u00e1s profunda sobre los materiales con los que se produce la ropa.<\/p>\n<p>Muchas prendas actuales est\u00e1n hechas con fibras sint\u00e9ticas derivadas del petr\u00f3leo, como el poli\u00e9ster, que liberan micropl\u00e1sticos durante el lavado.<\/p>\n<p>Por ello, el reto no es solo tecnol\u00f3gico, sino tambi\u00e9n relacionado con la forma en que producimos y consumimos ropa. En cualquier caso, es probable que el futuro combine innovaciones tecnol\u00f3gicas con nuevos modelos de uso compartido de los recursos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En esta primera sesi\u00f3n del Club de Innovadores 2026 exploramos el modelo de las cooperativas de vivienda con Pere Llorach, investigador, docente e ingeniero especializado en la intersecci\u00f3n entre el dise\u00f1o industrial, la sostenibilidad ambiental y la econom\u00eda circular. \u00bfPor qu\u00e9 el modelo de cooperativa de vivienda? Las cooperativas de vivienda son un modelo sin [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4101,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15],"class_list":["post-4108","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-club-de-innovadores"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pere Llorach Massana. Las cooperativas de vivienda: hacia un modelo m\u00e1s justo y sostenible - Girbau LAB<\/title>\n<meta name=\"description\" content=\"En esta primera sesi\u00f3n del Club de Innovadores 2026 exploramos el modelo de las cooperativas de vivienda con Pere Llorach\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pere Llorach Massana. Las cooperativas de vivienda: hacia un modelo m\u00e1s justo y sostenible - Girbau LAB\" \/>\n<meta property=\"og:description\" content=\"En esta primera sesi\u00f3n del Club de Innovadores 2026 exploramos el modelo de las cooperativas de vivienda con Pere Llorach\" \/>\n<meta property=\"og:url\" content=\"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/\" \/>\n<meta property=\"og:site_name\" content=\"Girbau LAB\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-10T23:42:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-11T00:04:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/03\/Pere_llorach.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1065\" \/>\n\t<meta property=\"og:image:height\" content=\"710\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"girbau\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@girbaulab\" \/>\n<meta name=\"twitter:site\" content=\"@girbaulab\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"girbau\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/\"},\"author\":{\"name\":\"girbau\",\"@id\":\"https:\/\/www.girbaulab.com\/es\/#\/schema\/person\/23b9b3863288ce7c33d38f38f3a3af5f\"},\"headline\":\"Pere Llorach Massana. Las cooperativas de vivienda: hacia un modelo m\u00e1s justo y sostenible\",\"datePublished\":\"2026-03-10T23:42:57+00:00\",\"dateModified\":\"2026-03-11T00:04:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/\"},\"wordCount\":1369,\"publisher\":{\"@id\":\"https:\/\/www.girbaulab.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/03\/Pere_llorach.jpg\",\"articleSection\":[\"Club de Innovadores\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/\",\"url\":\"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/\",\"name\":\"Pere Llorach Massana. Las cooperativas de vivienda: hacia un modelo m\u00e1s justo y sostenible - Girbau LAB\",\"isPartOf\":{\"@id\":\"https:\/\/www.girbaulab.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/03\/Pere_llorach.jpg\",\"datePublished\":\"2026-03-10T23:42:57+00:00\",\"dateModified\":\"2026-03-11T00:04:09+00:00\",\"description\":\"En esta primera sesi\u00f3n del Club de Innovadores 2026 exploramos el modelo de las cooperativas de vivienda con Pere Llorach\",\"breadcrumb\":{\"@id\":\"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/#primaryimage\",\"url\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/03\/Pere_llorach.jpg\",\"contentUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/03\/Pere_llorach.jpg\",\"width\":1065,\"height\":710,\"caption\":\"Pere Llorach Massana\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.girbaulab.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pere Llorach Massana. Las cooperativas de vivienda: hacia un modelo m\u00e1s justo y sostenible\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.girbaulab.com\/es\/#website\",\"url\":\"https:\/\/www.girbaulab.com\/es\/\",\"name\":\"Girbau LAB\",\"description\":\"Girbau LAB is a space for collaboration created to add value to the laundry industry through innovation\",\"publisher\":{\"@id\":\"https:\/\/www.girbaulab.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.girbaulab.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.girbaulab.com\/es\/#organization\",\"name\":\"Girbau LAB\",\"url\":\"https:\/\/www.girbaulab.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.girbaulab.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/10\/Girbau_LAB_logo.png\",\"contentUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/10\/Girbau_LAB_logo.png\",\"width\":562,\"height\":90,\"caption\":\"Girbau LAB\"},\"image\":{\"@id\":\"https:\/\/www.girbaulab.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/girbaulab\",\"https:\/\/www.linkedin.com\/company\/girbaulab\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.girbaulab.com\/es\/#\/schema\/person\/23b9b3863288ce7c33d38f38f3a3af5f\",\"name\":\"girbau\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.girbaulab.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fe57a3f139ea81c65a338e37a8064b4e80844f839737532820c9107eb9e1966f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fe57a3f139ea81c65a338e37a8064b4e80844f839737532820c9107eb9e1966f?s=96&d=mm&r=g\",\"caption\":\"girbau\"},\"sameAs\":[\"https:\/\/labs.100x100.net\/projects\/girbaulab\/private\"],\"url\":\"https:\/\/girbaulab.com\/es\/author\/girbau\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pere Llorach Massana. Las cooperativas de vivienda: hacia un modelo m\u00e1s justo y sostenible - Girbau LAB","description":"En esta primera sesi\u00f3n del Club de Innovadores 2026 exploramos el modelo de las cooperativas de vivienda con Pere Llorach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/","og_locale":"es_ES","og_type":"article","og_title":"Pere Llorach Massana. Las cooperativas de vivienda: hacia un modelo m\u00e1s justo y sostenible - Girbau LAB","og_description":"En esta primera sesi\u00f3n del Club de Innovadores 2026 exploramos el modelo de las cooperativas de vivienda con Pere Llorach","og_url":"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/","og_site_name":"Girbau LAB","article_published_time":"2026-03-10T23:42:57+00:00","article_modified_time":"2026-03-11T00:04:09+00:00","og_image":[{"width":1065,"height":710,"url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/03\/Pere_llorach.jpg","type":"image\/jpeg"}],"author":"girbau","twitter_card":"summary_large_image","twitter_creator":"@girbaulab","twitter_site":"@girbaulab","twitter_misc":{"Escrito por":"girbau","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/#article","isPartOf":{"@id":"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/"},"author":{"name":"girbau","@id":"https:\/\/www.girbaulab.com\/es\/#\/schema\/person\/23b9b3863288ce7c33d38f38f3a3af5f"},"headline":"Pere Llorach Massana. Las cooperativas de vivienda: hacia un modelo m\u00e1s justo y sostenible","datePublished":"2026-03-10T23:42:57+00:00","dateModified":"2026-03-11T00:04:09+00:00","mainEntityOfPage":{"@id":"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/"},"wordCount":1369,"publisher":{"@id":"https:\/\/www.girbaulab.com\/es\/#organization"},"image":{"@id":"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/#primaryimage"},"thumbnailUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/03\/Pere_llorach.jpg","articleSection":["Club de Innovadores"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/","url":"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/","name":"Pere Llorach Massana. Las cooperativas de vivienda: hacia un modelo m\u00e1s justo y sostenible - Girbau LAB","isPartOf":{"@id":"https:\/\/www.girbaulab.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/#primaryimage"},"image":{"@id":"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/#primaryimage"},"thumbnailUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/03\/Pere_llorach.jpg","datePublished":"2026-03-10T23:42:57+00:00","dateModified":"2026-03-11T00:04:09+00:00","description":"En esta primera sesi\u00f3n del Club de Innovadores 2026 exploramos el modelo de las cooperativas de vivienda con Pere Llorach","breadcrumb":{"@id":"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/#primaryimage","url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/03\/Pere_llorach.jpg","contentUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/03\/Pere_llorach.jpg","width":1065,"height":710,"caption":"Pere Llorach Massana"},{"@type":"BreadcrumbList","@id":"https:\/\/girbaulab.com\/es\/pere-llorach-massana-las-cooperativas-de-vivienda-hacia-un-modelo-mas-justo-y-sostenible\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.girbaulab.com\/es\/"},{"@type":"ListItem","position":2,"name":"Pere Llorach Massana. Las cooperativas de vivienda: hacia un modelo m\u00e1s justo y sostenible"}]},{"@type":"WebSite","@id":"https:\/\/www.girbaulab.com\/es\/#website","url":"https:\/\/www.girbaulab.com\/es\/","name":"Girbau LAB","description":"Girbau LAB is a space for collaboration created to add value to the laundry industry through innovation","publisher":{"@id":"https:\/\/www.girbaulab.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.girbaulab.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.girbaulab.com\/es\/#organization","name":"Girbau LAB","url":"https:\/\/www.girbaulab.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.girbaulab.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/10\/Girbau_LAB_logo.png","contentUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/10\/Girbau_LAB_logo.png","width":562,"height":90,"caption":"Girbau LAB"},"image":{"@id":"https:\/\/www.girbaulab.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/girbaulab","https:\/\/www.linkedin.com\/company\/girbaulab\/"]},{"@type":"Person","@id":"https:\/\/www.girbaulab.com\/es\/#\/schema\/person\/23b9b3863288ce7c33d38f38f3a3af5f","name":"girbau","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.girbaulab.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fe57a3f139ea81c65a338e37a8064b4e80844f839737532820c9107eb9e1966f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe57a3f139ea81c65a338e37a8064b4e80844f839737532820c9107eb9e1966f?s=96&d=mm&r=g","caption":"girbau"},"sameAs":["https:\/\/labs.100x100.net\/projects\/girbaulab\/private"],"url":"https:\/\/girbaulab.com\/es\/author\/girbau\/"}]}},"_links":{"self":[{"href":"https:\/\/girbaulab.com\/es\/wp-json\/wp\/v2\/posts\/4108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/girbaulab.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/girbaulab.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/girbaulab.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/girbaulab.com\/es\/wp-json\/wp\/v2\/comments?post=4108"}],"version-history":[{"count":4,"href":"https:\/\/girbaulab.com\/es\/wp-json\/wp\/v2\/posts\/4108\/revisions"}],"predecessor-version":[{"id":4113,"href":"https:\/\/girbaulab.com\/es\/wp-json\/wp\/v2\/posts\/4108\/revisions\/4113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/girbaulab.com\/es\/wp-json\/wp\/v2\/media\/4101"}],"wp:attachment":[{"href":"https:\/\/girbaulab.com\/es\/wp-json\/wp\/v2\/media?parent=4108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/girbaulab.com\/es\/wp-json\/wp\/v2\/categories?post=4108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}