{"id":4369,"date":"2026-05-11T07:17:48","date_gmt":"2026-05-11T07:17:48","guid":{"rendered":"https:\/\/girbaulab.com\/albert-beltran-redesigning-our-relationship-with-technology\/"},"modified":"2026-05-11T07:26:03","modified_gmt":"2026-05-11T07:26:03","slug":"albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia","status":"publish","type":"post","link":"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/","title":{"rendered":"Albert Beltran: redissenyant la nostra relaci\u00f3 amb la tecnologia"},"content":{"rendered":"<p>En aquesta nova sessi\u00f3 del <a href=\"https:\/\/girbaulab.com\/ca\/cultura\/club-innovadors\/\"><strong>Club d\u2019Innovadors 2026<\/strong><\/a>, conversem amb <strong>Albert Beltran, co fundador de <a href=\"https:\/\/www.thebalancephone.com\/ca\">Balance Phone<\/a><\/strong>, una iniciativa que replanteja la manera com ens relacionem amb la tecnologia i, en especial, amb el tel\u00e8fon m\u00f2bil.<\/p>\n<p>Albert va iniciar la seva traject\u00f2ria professional a <strong>Amazon<\/strong>, on durant tres anys va treballar en publicitat digital per a grans empreses. Aquesta experi\u00e8ncia li va permetre entendre des de dins com funcionen les plataformes digitals, quins incentius les mouen i de quina manera capten l\u2019atenci\u00f3 dels usuaris.<\/p>\n<p>Amb aquesta experi\u00e8ncia i mogut per una inquietud compartida amb el seu amic i soci Carlos sobre la relaci\u00f3 de les persones amb el m\u00f2bil i la falta d\u2019autoregulaci\u00f3 per limitar-ne l\u2019\u00fas, decideixen emprendre i funden<strong> Balance Phone<\/strong> amb l\u2019objectiu de crear eines que ajudin les persones a reduir les distraccions digitals, recuperar el focus i fer un \u00fas m\u00e9s conscient de la tecnologia. En aquesta entrevista parlem d\u2019atenci\u00f3, h\u00e0bits digitals i model de negoci.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4360\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran_07_PhotoGiselaJane-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran_07_PhotoGiselaJane-scaled.jpg 2560w, https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran_07_PhotoGiselaJane-300x200.jpg 300w, https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran_07_PhotoGiselaJane-1024x683.jpg 1024w, https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran_07_PhotoGiselaJane-768x512.jpg 768w, https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran_07_PhotoGiselaJane-1536x1024.jpg 1536w, https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran_07_PhotoGiselaJane-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p><strong>Com ha influ\u00eft la teva experi\u00e8ncia a Amazon en la manera com entens avui la relaci\u00f3 entre tecnologia i persones?<\/strong><\/p>\n<p>M\u2019ha ajudat a entendre molt millor els incentius de les grans tecnol\u00f2giques i els seus models de negoci, i com sovint aquests no prioritzen el benestar de l\u2019usuari. Crec que una tecnologia que respecti l\u2019usuari no nom\u00e9s \u00e9s possible, sin\u00f3 necess\u00e0ria.<\/p>\n<p><strong>Quin va ser el moment o la reflexi\u00f3 que et va portar a crear Balance Phone?<\/strong><\/p>\n<p>Va n\u00e9ixer de la frustraci\u00f3 personal d\u2019intentar canviar els nostres h\u00e0bits digitals i veure que no aconsegu\u00edem trobar cap soluci\u00f3 definitiva. Ens vam adonar que el problema no era nom\u00e9s de disciplina individual, sin\u00f3 tamb\u00e9 de com estan dissenyats els dispositius i les aplicacions.<\/p>\n<p><strong>Quin \u00e9s l\u2019objectiu principal de Balance Phone i quins han estat els principals reptes a l\u2019hora de fer-lo realitat?<\/strong><\/p>\n<p>L\u2019objectiu \u00e9s crear eines que ajudin les persones a combatre la crisi global d\u2019atenci\u00f3 que estem vivint, especialment latent en les noves generacions. Un dels principals reptes \u00e9s a nivell de percepci\u00f3: fer entendre que aquest problema existeix i que hi ha alternatives reals \u00e9s m\u00e9s complex del que sembla.<\/p>\n<p><strong>Com imagines el futur de la relaci\u00f3 entre persones i tecnologia, i quin paper hi pot tenir en els nostres h\u00e0bits i benestar?<\/strong><\/p>\n<p>Soc molt partidari que cada interacci\u00f3 amb la tecnologia hauria d\u2019aportar molt valor a l\u2019usuari. Com menys interaccions i m\u00e9s impacte positiu tinguin, millor. Avui la tecnologia ens acompanya sobretot des de l\u2019entreteniment i no tant des de la funcionalitat. La tecnologia \u00e9s massa potent i t\u00e9 massa potencial com per utilitzar-la de la manera com ho fem actualment.<\/p>\n<p><strong>Quines oportunitats d\u2019innovaci\u00f3 veus en \u00e0mbits quotidians com la cura de la roba, seguint aquesta l\u00f2gica de tecnologia m\u00e9s conscient?<\/strong><\/p>\n<p>Ho veig igual: la tecnologia hauria de servir perqu\u00e8 l\u2019usuari perdi el m\u00ednim temps possible i perqu\u00e8 els processos siguin cada vegada m\u00e9s sostenibles.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4363\" src=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran_01-scaled.jpg\" alt=\"Albert Beltran Co-Founder @ Balance Phone \" width=\"2560\" height=\"1706\" srcset=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran_01-scaled.jpg 2560w, https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran_01-300x200.jpg 300w, https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran_01-1024x683.jpg 1024w, https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran_01-768x512.jpg 768w, https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran_01-1536x1024.jpg 1536w, https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran_01-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En aquesta nova sessi\u00f3 del Club d\u2019Innovadors 2026, conversem amb Albert Beltran, co fundador de Balance Phone, una iniciativa que replanteja la manera com ens relacionem amb la tecnologia i, en especial, amb el tel\u00e8fon m\u00f2bil. Albert va iniciar la seva traject\u00f2ria professional a Amazon, on durant tres anys va treballar en publicitat digital per [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4358,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"class_list":["post-4369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-club-dinnovadors"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Albert Beltran: redissenyant la nostra relaci\u00f3 amb la tecnologia - Girbau LAB<\/title>\n<meta name=\"description\" content=\"Conversem amb Albert Beltran, co fundador de Balance Phone, una iniciativa que replanteja la manera com ens relacionem amb la tecnologia i, en especial, amb el tel\u00e8fon m\u00f2bil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Albert Beltran: redissenyant la nostra relaci\u00f3 amb la tecnologia - Girbau LAB\" \/>\n<meta property=\"og:description\" content=\"Conversem amb Albert Beltran, co fundador de Balance Phone, una iniciativa que replanteja la manera com ens relacionem amb la tecnologia i, en especial, amb el tel\u00e8fon m\u00f2bil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/\" \/>\n<meta property=\"og:site_name\" content=\"Girbau LAB\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T07:17:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T07:26:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1051\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"girbau\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@girbaulab\" \/>\n<meta name=\"twitter:site\" content=\"@girbaulab\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"girbau\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/\"},\"author\":{\"name\":\"girbau\",\"@id\":\"https:\/\/www.girbaulab.com\/es\/#\/schema\/person\/23b9b3863288ce7c33d38f38f3a3af5f\"},\"headline\":\"Albert Beltran: redissenyant la nostra relaci\u00f3 amb la tecnologia\",\"datePublished\":\"2026-05-11T07:17:48+00:00\",\"dateModified\":\"2026-05-11T07:26:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/\"},\"wordCount\":526,\"publisher\":{\"@id\":\"https:\/\/www.girbaulab.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran.jpg\",\"articleSection\":[\"Club d\u2019Innovadors\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/\",\"url\":\"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/\",\"name\":\"Albert Beltran: redissenyant la nostra relaci\u00f3 amb la tecnologia - Girbau LAB\",\"isPartOf\":{\"@id\":\"https:\/\/www.girbaulab.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran.jpg\",\"datePublished\":\"2026-05-11T07:17:48+00:00\",\"dateModified\":\"2026-05-11T07:26:03+00:00\",\"description\":\"Conversem amb Albert Beltran, co fundador de Balance Phone, una iniciativa que replanteja la manera com ens relacionem amb la tecnologia i, en especial, amb el tel\u00e8fon m\u00f2bil.\",\"breadcrumb\":{\"@id\":\"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/#primaryimage\",\"url\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran.jpg\",\"contentUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran.jpg\",\"width\":1051,\"height\":700,\"caption\":\"Albert Beltran Co-Founder @ Balance Phone\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/www.girbaulab.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Albert Beltran: redissenyant la nostra relaci\u00f3 amb la tecnologia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.girbaulab.com\/es\/#website\",\"url\":\"https:\/\/www.girbaulab.com\/es\/\",\"name\":\"Girbau LAB\",\"description\":\"Girbau LAB is a space for collaboration created to add value to the laundry industry through innovation\",\"publisher\":{\"@id\":\"https:\/\/www.girbaulab.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.girbaulab.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.girbaulab.com\/es\/#organization\",\"name\":\"Girbau LAB\",\"url\":\"https:\/\/www.girbaulab.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.girbaulab.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/10\/Girbau_LAB_logo.png\",\"contentUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/10\/Girbau_LAB_logo.png\",\"width\":562,\"height\":90,\"caption\":\"Girbau LAB\"},\"image\":{\"@id\":\"https:\/\/www.girbaulab.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/girbaulab\",\"https:\/\/www.linkedin.com\/company\/girbaulab\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.girbaulab.com\/es\/#\/schema\/person\/23b9b3863288ce7c33d38f38f3a3af5f\",\"name\":\"girbau\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.girbaulab.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fe57a3f139ea81c65a338e37a8064b4e80844f839737532820c9107eb9e1966f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fe57a3f139ea81c65a338e37a8064b4e80844f839737532820c9107eb9e1966f?s=96&d=mm&r=g\",\"caption\":\"girbau\"},\"sameAs\":[\"https:\/\/labs.100x100.net\/projects\/girbaulab\/private\"],\"url\":\"https:\/\/girbaulab.com\/ca\/author\/girbau\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Albert Beltran: redissenyant la nostra relaci\u00f3 amb la tecnologia - Girbau LAB","description":"Conversem amb Albert Beltran, co fundador de Balance Phone, una iniciativa que replanteja la manera com ens relacionem amb la tecnologia i, en especial, amb el tel\u00e8fon m\u00f2bil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/","og_locale":"ca_ES","og_type":"article","og_title":"Albert Beltran: redissenyant la nostra relaci\u00f3 amb la tecnologia - Girbau LAB","og_description":"Conversem amb Albert Beltran, co fundador de Balance Phone, una iniciativa que replanteja la manera com ens relacionem amb la tecnologia i, en especial, amb el tel\u00e8fon m\u00f2bil.","og_url":"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/","og_site_name":"Girbau LAB","article_published_time":"2026-05-11T07:17:48+00:00","article_modified_time":"2026-05-11T07:26:03+00:00","og_image":[{"width":1051,"height":700,"url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran.jpg","type":"image\/jpeg"}],"author":"girbau","twitter_card":"summary_large_image","twitter_creator":"@girbaulab","twitter_site":"@girbaulab","twitter_misc":{"Written by":"girbau","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/#article","isPartOf":{"@id":"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/"},"author":{"name":"girbau","@id":"https:\/\/www.girbaulab.com\/es\/#\/schema\/person\/23b9b3863288ce7c33d38f38f3a3af5f"},"headline":"Albert Beltran: redissenyant la nostra relaci\u00f3 amb la tecnologia","datePublished":"2026-05-11T07:17:48+00:00","dateModified":"2026-05-11T07:26:03+00:00","mainEntityOfPage":{"@id":"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/"},"wordCount":526,"publisher":{"@id":"https:\/\/www.girbaulab.com\/es\/#organization"},"image":{"@id":"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/#primaryimage"},"thumbnailUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran.jpg","articleSection":["Club d\u2019Innovadors"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/","url":"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/","name":"Albert Beltran: redissenyant la nostra relaci\u00f3 amb la tecnologia - Girbau LAB","isPartOf":{"@id":"https:\/\/www.girbaulab.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/#primaryimage"},"image":{"@id":"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/#primaryimage"},"thumbnailUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran.jpg","datePublished":"2026-05-11T07:17:48+00:00","dateModified":"2026-05-11T07:26:03+00:00","description":"Conversem amb Albert Beltran, co fundador de Balance Phone, una iniciativa que replanteja la manera com ens relacionem amb la tecnologia i, en especial, amb el tel\u00e8fon m\u00f2bil.","breadcrumb":{"@id":"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/#primaryimage","url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran.jpg","contentUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2026\/05\/Albert_Beltran.jpg","width":1051,"height":700,"caption":"Albert Beltran Co-Founder @ Balance Phone"},{"@type":"BreadcrumbList","@id":"https:\/\/girbaulab.com\/ca\/albert-beltran-redissenyant-la-nostra-relacio-amb-la-tecnologia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.girbaulab.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Albert Beltran: redissenyant la nostra relaci\u00f3 amb la tecnologia"}]},{"@type":"WebSite","@id":"https:\/\/www.girbaulab.com\/es\/#website","url":"https:\/\/www.girbaulab.com\/es\/","name":"Girbau LAB","description":"Girbau LAB is a space for collaboration created to add value to the laundry industry through innovation","publisher":{"@id":"https:\/\/www.girbaulab.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.girbaulab.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.girbaulab.com\/es\/#organization","name":"Girbau LAB","url":"https:\/\/www.girbaulab.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.girbaulab.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/10\/Girbau_LAB_logo.png","contentUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/10\/Girbau_LAB_logo.png","width":562,"height":90,"caption":"Girbau LAB"},"image":{"@id":"https:\/\/www.girbaulab.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/girbaulab","https:\/\/www.linkedin.com\/company\/girbaulab\/"]},{"@type":"Person","@id":"https:\/\/www.girbaulab.com\/es\/#\/schema\/person\/23b9b3863288ce7c33d38f38f3a3af5f","name":"girbau","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.girbaulab.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fe57a3f139ea81c65a338e37a8064b4e80844f839737532820c9107eb9e1966f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe57a3f139ea81c65a338e37a8064b4e80844f839737532820c9107eb9e1966f?s=96&d=mm&r=g","caption":"girbau"},"sameAs":["https:\/\/labs.100x100.net\/projects\/girbaulab\/private"],"url":"https:\/\/girbaulab.com\/ca\/author\/girbau\/"}]}},"_links":{"self":[{"href":"https:\/\/girbaulab.com\/ca\/wp-json\/wp\/v2\/posts\/4369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/girbaulab.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/girbaulab.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/girbaulab.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/girbaulab.com\/ca\/wp-json\/wp\/v2\/comments?post=4369"}],"version-history":[{"count":3,"href":"https:\/\/girbaulab.com\/ca\/wp-json\/wp\/v2\/posts\/4369\/revisions"}],"predecessor-version":[{"id":4377,"href":"https:\/\/girbaulab.com\/ca\/wp-json\/wp\/v2\/posts\/4369\/revisions\/4377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/girbaulab.com\/ca\/wp-json\/wp\/v2\/media\/4358"}],"wp:attachment":[{"href":"https:\/\/girbaulab.com\/ca\/wp-json\/wp\/v2\/media?parent=4369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/girbaulab.com\/ca\/wp-json\/wp\/v2\/categories?post=4369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}